{"id":11074,"date":"2025-02-14T11:16:05","date_gmt":"2025-02-14T10:16:05","guid":{"rendered":"https:\/\/www.architetturaecologica.net\/?p=11074"},"modified":"2025-03-12T10:13:17","modified_gmt":"2025-03-12T09:13:17","slug":"edificio-rurale-in-sasso","status":"publish","type":"post","link":"https:\/\/www.architetturaecologica.net\/en\/edificio-rurale-in-sasso\/","title":{"rendered":"EDIFICIO RURALE IN SASSO"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">RISTRUTTURAZIONE ED EFFICIENTAMENTO ENERGETICO DI UN IMMOBILE SUI COLLI EUGANEI &#8211; PADOVA<\/h3>\n\n\n\n<p>Una abitazione rurale di fine \u2018800 che giace sul versante soleggiato di una verde valletta terrazzata a vite all\u2019interno di un\u2019area di riserva naturale dei Colli Euganei. Il progetto prevede la ristrutturazione e l\u2019<strong>efficientamento energetico <\/strong>in armonia con la progettazione paesaggistica delle aree limitrofe rispettando i caratteri di un\u2019abitazione rustica, semplice e frugale ma altamente performante dal punto di vista energetico.<\/p>\n\n\n\n<p>Il miglioramento antisismico, la rimodulazione e riordino di molti ambiti del paesaggio circostante, una impiantistica sofisticata sono alcuni degli ingredienti di quella che viene definita&nbsp;<em>\u201dla progettazione architettonica integrata\u201d<\/em>. Un team progettuale che dobbiamo coordinare durante la direzione dei lavori per armonizzare tutti i contributi professionali necessari ad una <strong>riqualificazione energetica<\/strong> di alto livello.&nbsp;<\/p>\n\n\n\n<p>La tecnologia costruttiva utilizzata \u00e8 quella di un telaio in carpenteria metallica completato con i tamponamenti perimetrali in mattoni pieni di <strong>calce canapa<\/strong>: solai e copertura -opportunamente isolata &#8211;&nbsp; in legno. Questa scelta determina un <strong>microclima<\/strong> interno di eccezionale livello sia invernale che estivo, grazie alle caratteristiche di questo materiale che abbina alle capacit\u00e0 isolanti necessarie per difendersi dal freddo, una massa pesante che protegge dal calore estivo.<\/p>\n\n\n\n<p>Per le pavimentazioni si \u00e8 scelto di utilizzare, all\u2019interno, una pietra locale a km zero, proveniente da una cava situata a poche centinaia di metri dal cantiere e di riutilizzare, per i selciati esterni, tutte le pietre ricavate dalla demolizione della porzione di casa inagibile.<\/p>\n\n\n\n<p>Intonaci in <strong>calce<\/strong>, legnami finiti ad olio, pitture <strong>ecologiche<\/strong> e traspiranti concorrono a creare un ottimo microclima igrotermico.<\/p>\n\n\n\n<p>Il luogo, la luce, il silenzio fanno tutto il resto, che \u00e8 moltissimo.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RISTRUTTURAZIONE ED EFFICIENTAMENTO ENERGETICO DI UN IMMOBILE SUI COLLI EUGANEI &#8211; PADOVA Una abitazione rurale di fine \u2018800 che giace sul versante soleggiato di una verde valletta terrazzata a vite all\u2019interno di un\u2019area di riserva naturale dei Colli Euganei. Il progetto prevede la ristrutturazione e l\u2019efficientamento energetico in armonia con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,167,164],"tags":[],"class_list":["post-11074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-efficienza-energetica","category-riqualificazione-energetica","category-ristrutturazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EDIFICIO RURALE IN SASSO - LAe - Laboratorio di Architettura Ecologica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EDIFICIO RURALE IN SASSO - LAe - Laboratorio di Architettura Ecologica\" \/>\n<meta property=\"og:description\" content=\"RISTRUTTURAZIONE ED EFFICIENTAMENTO ENERGETICO DI UN IMMOBILE SUI COLLI EUGANEI &#8211; PADOVA Una abitazione rurale di fine \u2018800 che giace sul versante soleggiato di una verde valletta terrazzata a vite all\u2019interno di un\u2019area di riserva naturale dei Colli Euganei. Il progetto prevede la ristrutturazione e l\u2019efficientamento energetico in armonia con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/\" \/>\n<meta property=\"og:site_name\" content=\"LAe - Laboratorio di Architettura Ecologica\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T10:16:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T09:13:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.architetturaecologica.net\/wp-content\/uploads\/2025\/02\/20250210_bdo-blog2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"910\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"LAe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LAe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/\"},\"author\":{\"name\":\"LAe\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/#\\\/schema\\\/person\\\/073378d257c50398fa05c5b9b68f8398\"},\"headline\":\"EDIFICIO RURALE IN SASSO\",\"datePublished\":\"2025-02-14T10:16:05+00:00\",\"dateModified\":\"2025-03-12T09:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/\"},\"wordCount\":279,\"image\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.architetturaecologica.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210_bdo-blog2.png\",\"articleSection\":[\"Efficienza Energetica\",\"Riqualificazione Energetica\",\"Ristrutturazione\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/\",\"url\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/\",\"name\":\"EDIFICIO RURALE IN SASSO - LAe - Laboratorio di Architettura Ecologica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.architetturaecologica.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210_bdo-blog2.png\",\"datePublished\":\"2025-02-14T10:16:05+00:00\",\"dateModified\":\"2025-03-12T09:13:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/#\\\/schema\\\/person\\\/073378d257c50398fa05c5b9b68f8398\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.architetturaecologica.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210_bdo-blog2.png\",\"contentUrl\":\"https:\\\/\\\/www.architetturaecologica.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/20250210_bdo-blog2.png\",\"width\":1365,\"height\":910},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/edificio-rurale-in-sasso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.architetturaecologica.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EDIFICIO RURALE IN SASSO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/#website\",\"url\":\"https:\\\/\\\/www.architetturaecologica.net\\\/\",\"name\":\"LAe - Laboratorio di Architettura Ecologica\",\"description\":\"L&#039;abitare del futuro \u00e8 sostenibile\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.architetturaecologica.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.architetturaecologica.net\\\/#\\\/schema\\\/person\\\/073378d257c50398fa05c5b9b68f8398\",\"name\":\"LAe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8153e1a2e1170ec00429ee7ad6b40471e0c1ae13178b1602a40031be333bfec3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8153e1a2e1170ec00429ee7ad6b40471e0c1ae13178b1602a40031be333bfec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8153e1a2e1170ec00429ee7ad6b40471e0c1ae13178b1602a40031be333bfec3?s=96&d=mm&r=g\",\"caption\":\"LAe\"},\"url\":\"https:\\\/\\\/www.architetturaecologica.net\\\/en\\\/author\\\/alessandra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EDIFICIO RURALE IN SASSO - LAe - Laboratorio di Architettura Ecologica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/","og_locale":"en_US","og_type":"article","og_title":"EDIFICIO RURALE IN SASSO - LAe - Laboratorio di Architettura Ecologica","og_description":"RISTRUTTURAZIONE ED EFFICIENTAMENTO ENERGETICO DI UN IMMOBILE SUI COLLI EUGANEI &#8211; PADOVA Una abitazione rurale di fine \u2018800 che giace sul versante soleggiato di una verde valletta terrazzata a vite all\u2019interno di un\u2019area di riserva naturale dei Colli Euganei. Il progetto prevede la ristrutturazione e l\u2019efficientamento energetico in armonia con [&hellip;]","og_url":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/","og_site_name":"LAe - Laboratorio di Architettura Ecologica","article_published_time":"2025-02-14T10:16:05+00:00","article_modified_time":"2025-03-12T09:13:17+00:00","og_image":[{"width":1365,"height":910,"url":"https:\/\/www.architetturaecologica.net\/wp-content\/uploads\/2025\/02\/20250210_bdo-blog2.png","type":"image\/png"}],"author":"LAe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"LAe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#article","isPartOf":{"@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/"},"author":{"name":"LAe","@id":"https:\/\/www.architetturaecologica.net\/#\/schema\/person\/073378d257c50398fa05c5b9b68f8398"},"headline":"EDIFICIO RURALE IN SASSO","datePublished":"2025-02-14T10:16:05+00:00","dateModified":"2025-03-12T09:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/"},"wordCount":279,"image":{"@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.architetturaecologica.net\/wp-content\/uploads\/2025\/02\/20250210_bdo-blog2.png","articleSection":["Efficienza Energetica","Riqualificazione Energetica","Ristrutturazione"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/","url":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/","name":"EDIFICIO RURALE IN SASSO - LAe - Laboratorio di Architettura Ecologica","isPartOf":{"@id":"https:\/\/www.architetturaecologica.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#primaryimage"},"image":{"@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.architetturaecologica.net\/wp-content\/uploads\/2025\/02\/20250210_bdo-blog2.png","datePublished":"2025-02-14T10:16:05+00:00","dateModified":"2025-03-12T09:13:17+00:00","author":{"@id":"https:\/\/www.architetturaecologica.net\/#\/schema\/person\/073378d257c50398fa05c5b9b68f8398"},"breadcrumb":{"@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#primaryimage","url":"https:\/\/www.architetturaecologica.net\/wp-content\/uploads\/2025\/02\/20250210_bdo-blog2.png","contentUrl":"https:\/\/www.architetturaecologica.net\/wp-content\/uploads\/2025\/02\/20250210_bdo-blog2.png","width":1365,"height":910},{"@type":"BreadcrumbList","@id":"https:\/\/www.architetturaecologica.net\/edificio-rurale-in-sasso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.architetturaecologica.net\/en\/"},{"@type":"ListItem","position":2,"name":"EDIFICIO RURALE IN SASSO"}]},{"@type":"WebSite","@id":"https:\/\/www.architetturaecologica.net\/#website","url":"https:\/\/www.architetturaecologica.net\/","name":"LAe - Laboratorio di Architettura Ecologica","description":"L&#039;abitare del futuro \u00e8 sostenibile","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.architetturaecologica.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.architetturaecologica.net\/#\/schema\/person\/073378d257c50398fa05c5b9b68f8398","name":"LAe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8153e1a2e1170ec00429ee7ad6b40471e0c1ae13178b1602a40031be333bfec3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8153e1a2e1170ec00429ee7ad6b40471e0c1ae13178b1602a40031be333bfec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8153e1a2e1170ec00429ee7ad6b40471e0c1ae13178b1602a40031be333bfec3?s=96&d=mm&r=g","caption":"LAe"},"url":"https:\/\/www.architetturaecologica.net\/en\/author\/alessandra\/"}]}},"_links":{"self":[{"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/posts\/11074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/comments?post=11074"}],"version-history":[{"count":1,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/posts\/11074\/revisions"}],"predecessor-version":[{"id":11077,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/posts\/11074\/revisions\/11077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/media\/11089"}],"wp:attachment":[{"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/media?parent=11074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/categories?post=11074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.architetturaecologica.net\/en\/wp-json\/wp\/v2\/tags?post=11074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}